{"id":22203,"date":"2023-12-12T14:57:45","date_gmt":"2023-12-12T14:57:45","guid":{"rendered":"https:\/\/www.medienlb.com\/produkt\/html5-grundlagen-mit-css\/"},"modified":"2024-02-14T14:58:09","modified_gmt":"2024-02-14T14:58:09","slug":"html5-grundlagen-mit-css","status":"publish","type":"product","link":"https:\/\/www.medienlb.com\/en\/produkt\/html5-grundlagen-mit-css\/","title":{"rendered":"HTML5 Grundlagen mit CSS"},"content":{"rendered":"<p>F\u00fcr den Unterrichtempfohlen<\/p>\n<p>In unserem Arbeitsheft Informatik 7-8, Vol. 1 &#8211; HTML5 Grundlagen mit CSS finden Sie 50 interaktive und didaktisch aufbereitete H5P-Module.<br \/>\nDas Medium bietet H5P-Aufgaben an, die ohne zus\u00e4tzliche Software verwendbar sind. Es enth\u00e4lt zahlreiche interaktive Aufgaben zum Thema: HTML5 Grundlagen mit CSS.<br \/>\nDurch interaktive Aufgabentypen wird das audiovisuelle und interaktive Lernen einfach.<\/p>\n<p>Lernen macht jetzt Spa\u00df!\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr den Unterrichtempfohlen<\/p>\n","protected":false},"featured_media":19240,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[183],"product_tag":[155,157,106,144],"class_list":{"0":"post-22203","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-interactive-workbook","7":"product_tag-old_image-2","8":"product_tag-subject-informatik-2","9":"product_tag-subject-technology","10":"product_tag-target-lehrer-2","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"acf":{"subtitle":"","article_id":"55501368","languages":"DE","thumb_up":true,"cover_image":null,"linked_product":null,"linked_products":null,"banner":{"show":false,"text":"","color":""},"length":"","content_movie":"","learning_goals":"","preview_gif":null,"trailer":{"file":null,"url":"","image":null},"mediathek_id":"","amount":50,"demo_url":"","h5p_demo_id":"","content_interactive":"1. HTML - Was ist HTML? - Interaktive Wissensvermittlung\n2. HTML - Editor - Interaktive Wissensvermittlung\n3. HTML - Grundlagen - Das Basiswissen\n4. HTML - Elemente - Interaktive Wissensvermittlung\n5. HTML - Text-Formatierungselemente - Interaktive Wissensvermittlung\n6. HTML - Style - Interaktive Wissensvermittlung\n7. HTML - Zitat- und Zitierelemente - Interaktive Wissensvermittlung\n8. HTML - Seite mit Schritt-f\u00fcr-Schritt Anleitung erstellen!\n9. HTML - ungeordnete Listen - Interaktive Wissensvermittlung\n10. HTML - geordnete Listen - Interaktive Wissensvermittlung \n11. HTML - Block- und Inline-Elemente - Interaktive Wissensvermittlung \n12. HTML - Bilder - Interaktive Wissensvermittlung \n13. HTML - Kommentare - Interaktive Wissensvermittlung \n14. HTML Grundlagen - Abs\u00e4tze - 5 Interaktive Aufgaben (1) \n15. HTML Grundlagen - Attribute - 5 interaktive Aufgaben (2) \n16. HTML Grundlagen - 5 interaktive Aufgaben (1) \n17. HTML Grundlagen - 5 interaktive Aufgaben (2) \n18. HTML Grundlagen - 5 interaktive Aufgaben (3) \n19. HTML Grundlagen - 5 interaktive Aufgaben (4) \n20. HTML Grundlagen - 5 interaktive Aufgaben (5) \n21. HTML Grundlagen - 5 interaktive Aufgaben (6) \n22. HTML Grundlagen - 5 interaktive Aufgaben (7) \n23. HTML - Style - 5 interaktive Aufgaben (1) \n24. HTML - Style - 5 interaktive Aufgaben (2) \n25. HTML - Formatierung - 5 interaktive Aufgaben (1)\n26. HTML - Formatierung - 5 interaktive Aufgaben (2) \n27. HTML - Listen - Interaktive Aufgaben (1) \n28. HTML - Listen - Interaktive Aufgaben (2) \n30. HTML - Style\/Formatierung - 5 interaktive Aufgaben (1) 30. HTML - Style\/Formatierung - 5 interaktive Aufgaben (2) \n31. HTML - Style\/Formatierung - 5 interaktive Aufgaben (3) \n32. Ordne die Tags den entsprechenden Bedeutungen zu! \n33. HTML - Codezeilen - 5 interaktive Aufgaben (1) \n34. HTML - Codezeilen - 5 interaktive Aufgaben (2) \n35. Bewerte die folgenden HTML-Codezeilen\/Aussagen (1) \n36. Bewerte die folgenden HTML-Codezeilen\/Aussagen (2) \n37. Bewerte die folgenden HTML-Codezeilen\/Aussagen (3) \n38. Kennst du die korrekten HTML-Elemente? (1) \n39. Kennst du die korrekten HTML-Elemente? (2) \n40. Sortiere die Code-Fragmente in die richtige Reihenfolge! (1) \n41. Sortiere die Code-Fragmente in die richtige Reihenfolge! (2) \n42. HTML-Praxis: Code erg\u00e4nzen - Interaktive Aufgaben (1) \n43. HTML-Praxis: Code erg\u00e4nzen - Interaktive Aufgaben (2) \n44. HTML-Praxis: Code erg\u00e4nzen - Interaktive Aufgaben (3) \n45. HTML-Praxis: Code erg\u00e4nzen - Interaktive Aufgaben (4) \n46. Ordne die HTML-Tags korrekt zu! - Interaktive Aufgabe (1) \n47. Ordne die HTML-Tags korrekt zu! - Interaktive Aufgabe (2) \n48. Eine HTML-Webseite erstellen - Praxistest - Aufgabe (1) \n49. Eine HTML-Webseite erstellen - Praxistest - Aufgabe (2) \n50. 20 Tags und deren Bedeutung - Finde die Bildpaare","hide_numbers":true,"flyer":null,"info_columns":null},"_links":{"self":[{"href":"https:\/\/www.medienlb.com\/en\/wp-json\/wp\/v2\/product\/22203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medienlb.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.medienlb.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medienlb.com\/en\/wp-json\/wp\/v2\/media\/19240"}],"wp:attachment":[{"href":"https:\/\/www.medienlb.com\/en\/wp-json\/wp\/v2\/media?parent=22203"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.medienlb.com\/en\/wp-json\/wp\/v2\/product_brand?post=22203"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.medienlb.com\/en\/wp-json\/wp\/v2\/product_cat?post=22203"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.medienlb.com\/en\/wp-json\/wp\/v2\/product_tag?post=22203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}